{"id":4451,"date":"2023-01-06T07:00:15","date_gmt":"2023-01-06T06:00:15","guid":{"rendered":"http:\/\/nivernaise.wakemeup-dns.com\/?post_type=product&#038;p=4451"},"modified":"2025-04-08T15:23:31","modified_gmt":"2025-04-08T13:23:31","slug":"summer-barbecue-box","status":"publish","type":"product","link":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/","title":{"rendered":"Summer Barbecue Box"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;We have selected a perfect set for your summer barbecues with family or friends. It includes eight types of meats chosen by our head butcher, as well as two fuet sausages to enhance your appetizer.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14781,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:1,&quot;11&quot;:4,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:18}\">We have selected a perfect set for your summer barbecues with family or friends. It includes eight types of meats chosen by our head butcher, as well as two fuet sausages to enhance your appetizer.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>We have selected a perfect set for your summer barbecues with family or friends. It includes eight types of meats chosen by our head butcher, as well as two fuet sausages to enhance your appetizer.<\/p>\n","protected":false},"featured_media":4452,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[45],"product_tag":[],"class_list":["post-4451","product","type-product","status-publish","has-post-thumbnail","product_cat-boxes","product_shipping_class-fresh-product","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Summer Barbecue Box - Les Boucheries Nivernaises<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Summer Barbecue Box - Les Boucheries Nivernaises\" \/>\n<meta property=\"og:description\" content=\"We have selected a perfect set for your summer barbecues with family or friends. It includes eight types of meats chosen by our head butcher, as well as two fuet sausages to enhance your appetizer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Boucheries Nivernaises\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T13:23:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/\",\"name\":\"Summer Barbecue Box - Les Boucheries Nivernaises\",\"isPartOf\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp\",\"datePublished\":\"2023-01-06T06:00:15+00:00\",\"dateModified\":\"2025-04-08T13:23:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#primaryimage\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp\",\"contentUrl\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp\",\"width\":800,\"height\":571},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop online\",\"item\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/shop-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Summer Barbecue Box\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/\",\"name\":\"Les Boucheries Nivernaises\",\"description\":\"DEV\",\"publisher\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization\",\"name\":\"Les Boucheries Nivernaises\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg\",\"contentUrl\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg\",\"width\":581.9,\"height\":36.09,\"caption\":\"Les Boucheries Nivernaises\"},\"image\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Summer Barbecue Box - Les Boucheries Nivernaises","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Summer Barbecue Box - Les Boucheries Nivernaises","og_description":"We have selected a perfect set for your summer barbecues with family or friends. It includes eight types of meats chosen by our head butcher, as well as two fuet sausages to enhance your appetizer.","og_url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/","og_site_name":"Les Boucheries Nivernaises","article_modified_time":"2025-04-08T13:23:31+00:00","og_image":[{"width":800,"height":571,"url":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/","url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/","name":"Summer Barbecue Box - Les Boucheries Nivernaises","isPartOf":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#primaryimage"},"image":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#primaryimage"},"thumbnailUrl":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp","datePublished":"2023-01-06T06:00:15+00:00","dateModified":"2025-04-08T13:23:31+00:00","breadcrumb":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#primaryimage","url":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp","contentUrl":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Summer-Barbecue-Box.webp","width":800,"height":571},{"@type":"BreadcrumbList","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/summer-barbecue-box\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nivernaise.wakemeup-dns.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop online","item":"https:\/\/nivernaise.wakemeup-dns.com\/en\/shop-online\/"},{"@type":"ListItem","position":3,"name":"Summer Barbecue Box"}]},{"@type":"WebSite","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website","url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/","name":"Les Boucheries Nivernaises","description":"DEV","publisher":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nivernaise.wakemeup-dns.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization","name":"Les Boucheries Nivernaises","url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg","contentUrl":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg","width":581.9,"height":36.09,"caption":"Les Boucheries Nivernaises"},"image":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product\/4451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/comments?post=4451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/media\/4452"}],"wp:attachment":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/media?parent=4451"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product_brand?post=4451"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product_cat?post=4451"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product_tag?post=4451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}