{"id":1776,"date":"2023-10-23T16:26:04","date_gmt":"2023-10-23T16:26:04","guid":{"rendered":"http:\/\/nivernaise.wakemeup-dns.com\/?post_type=product&#038;p=1776"},"modified":"2025-03-02T19:00:17","modified_gmt":"2025-03-02T18:00:17","slug":"shredded-confit-duck","status":"publish","type":"product","link":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/","title":{"rendered":"Shredded Confit Duck"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;This is a package of boneless, skinless shredded duck thigh confit. The meat is slowly cooked in its own fat until it becomes tender and juicy. This cooking method gives the duck meat a melting texture and a rich, delicious flavor.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14781,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:1,&quot;11&quot;:4,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:18}\">This is a package of boneless, skinless shredded duck thigh confit. The meat is slowly cooked in its own fat until it becomes tender and juicy. This cooking method gives the duck meat a melting texture and a rich, delicious flavor.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>This is a package of boneless, skinless shredded duck thigh confit. The meat is slowly cooked in its own fat until it becomes tender and juicy. This cooking method gives the duck meat a melting texture and a rich, delicious flavor.<\/p>\n","protected":false},"featured_media":1777,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[123,32,86],"product_tag":[],"class_list":["post-1776","product","type-product","status-publish","has-post-thumbnail","product_cat-new-in-2025","product_cat-poultry","product_cat-new-in","product_shipping_class-fresh-product","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Shredded Confit Duck - Les Boucheries Nivernaises<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shredded Confit Duck - Les Boucheries Nivernaises\" \/>\n<meta property=\"og:description\" content=\"This is a package of boneless, skinless shredded duck thigh confit. The meat is slowly cooked in its own fat until it becomes tender and juicy. This cooking method gives the duck meat a melting texture and a rich, delicious flavor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Boucheries Nivernaises\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T18:00:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/\",\"name\":\"Shredded Confit Duck - Les Boucheries Nivernaises\",\"isPartOf\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp\",\"datePublished\":\"2023-10-23T16:26:04+00:00\",\"dateModified\":\"2025-03-02T18:00:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#primaryimage\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp\",\"contentUrl\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp\",\"width\":720,\"height\":518},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop online\",\"item\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/shop-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shredded Confit Duck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/\",\"name\":\"Les Boucheries Nivernaises\",\"description\":\"DEV\",\"publisher\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization\",\"name\":\"Les Boucheries Nivernaises\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg\",\"contentUrl\":\"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg\",\"width\":581.9,\"height\":36.09,\"caption\":\"Les Boucheries Nivernaises\"},\"image\":{\"@id\":\"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shredded Confit Duck - Les Boucheries Nivernaises","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Shredded Confit Duck - Les Boucheries Nivernaises","og_description":"This is a package of boneless, skinless shredded duck thigh confit. The meat is slowly cooked in its own fat until it becomes tender and juicy. This cooking method gives the duck meat a melting texture and a rich, delicious flavor.","og_url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/","og_site_name":"Les Boucheries Nivernaises","article_modified_time":"2025-03-02T18:00:17+00:00","og_image":[{"width":720,"height":518,"url":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/","url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/","name":"Shredded Confit Duck - Les Boucheries Nivernaises","isPartOf":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#primaryimage"},"image":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#primaryimage"},"thumbnailUrl":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp","datePublished":"2023-10-23T16:26:04+00:00","dateModified":"2025-03-02T18:00:17+00:00","breadcrumb":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#primaryimage","url":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp","contentUrl":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/Shredded-Confit-Duck.webp","width":720,"height":518},{"@type":"BreadcrumbList","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/product\/shredded-confit-duck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nivernaise.wakemeup-dns.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop online","item":"https:\/\/nivernaise.wakemeup-dns.com\/en\/shop-online\/"},{"@type":"ListItem","position":3,"name":"Shredded Confit Duck"}]},{"@type":"WebSite","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#website","url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/","name":"Les Boucheries Nivernaises","description":"DEV","publisher":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nivernaise.wakemeup-dns.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#organization","name":"Les Boucheries Nivernaises","url":"https:\/\/nivernaise.wakemeup-dns.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg","contentUrl":"https:\/\/nivernaise.wakemeup-dns.com\/wp-content\/uploads\/boucheriesnivernaises-logo.svg","width":581.9,"height":36.09,"caption":"Les Boucheries Nivernaises"},"image":{"@id":"https:\/\/nivernaise.wakemeup-dns.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product\/1776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/comments?post=1776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/media\/1777"}],"wp:attachment":[{"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/media?parent=1776"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product_brand?post=1776"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product_cat?post=1776"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nivernaise.wakemeup-dns.com\/en\/wp-json\/wp\/v2\/product_tag?post=1776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}